{"id":513,"count":1,"description":"","link":"https:\/\/www.englishcentral.com\/blog\/vi\/tag\/trich-dan-cho-instagram\/","name":"tr\u00edch d\u1eabn cho instagram","slug":"trich-dan-cho-instagram","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.englishcentral.com\/blog\/wp-json\/wp\/v2\/tags\/513","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.englishcentral.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.englishcentral.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.englishcentral.com\/blog\/wp-json\/wp\/v2\/posts?tags=513"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}